{"id":70240,"date":"2022-07-04T17:02:36","date_gmt":"2022-07-04T15:02:36","guid":{"rendered":"https:\/\/bannedvideos.net\/candida-infektion-und-ein-ausweg\/"},"modified":"2023-03-07T20:23:46","modified_gmt":"2023-03-07T18:23:46","slug":"candida-infektion-und-ein-ausweg","status":"publish","type":"post","link":"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/","title":{"rendered":"Candida-Infektion und ein Ausweg"},"content":{"rendered":"<p>Neben einer Candida-Infektion litt Hajnalka seit ihrem 12. Lebensjahr an Skoliose. Die beiden unterschiedlichen Probleme hatten sich seit Jahren gegenseitig beeinflusst. Hajnalka erz\u00e4hlt ihre Geschichte dar\u00fcber, wie sie es geschafft hat, sich nach vielen Jahren zu erholen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neben einer Candida-Infektion litt Hajnalka seit ihrem 12. Lebensjahr an Skoliose. Die beiden unterschiedlichen Probleme hatten sich seit Jahren gegenseitig beeinflusst. Hajnalka erz\u00e4hlt ihre Geschichte dar\u00fcber, wie sie es geschafft hat, sich nach vielen Jahren zu erholen.<\/p>\n","protected":false},"author":4,"featured_media":70241,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[331,612],"tags":[],"class_list":{"0":"post-70240","1":"post","2":"type-post","3":"status-publish","4":"format-video","5":"has-post-thumbnail","7":"category-darmprobleme","8":"category-wirbelsaulenprobleme","9":"post_format-post-format-video"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Candida-Infektion und ein Ausweg - Banned videos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Candida-Infektion und ein Ausweg - Banned videos\" \/>\n<meta property=\"og:description\" content=\"Neben einer Candida-Infektion litt Hajnalka seit ihrem 12. Lebensjahr an Skoliose. Die beiden unterschiedlichen Probleme hatten sich seit Jahren gegenseitig beeinflusst. Hajnalka erz\u00e4hlt ihre Geschichte dar\u00fcber, wie sie es geschafft hat, sich nach vielen Jahren zu erholen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/\" \/>\n<meta property=\"og:site_name\" content=\"Banned videos\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-04T15:02:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-07T18:23:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2023\/03\/803461288.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"295\" \/>\n\t<meta property=\"og:image:height\" content=\"166\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bannedvideos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"bannedvideos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"ScholarlyArticle\",\"@id\":\"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/\"},\"author\":{\"name\":\"bannedvideos\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/6901bae47f89066856a9d2c7faa5ebd2\"},\"headline\":\"Candida-Infektion und ein Ausweg\",\"datePublished\":\"2022-07-04T15:02:36+00:00\",\"dateModified\":\"2023-03-07T18:23:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/\"},\"wordCount\":42,\"publisher\":{\"@id\":\"https:\/\/bannedvideos.net\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2023\/03\/803461288.jpg\",\"articleSection\":[\"Darmprobleme\",\"Wirbels\u00e4ulenprobleme\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/\",\"url\":\"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/\",\"name\":\"Candida-Infektion und ein Ausweg - Banned videos\",\"isPartOf\":{\"@id\":\"https:\/\/bannedvideos.net\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2023\/03\/803461288.jpg\",\"datePublished\":\"2022-07-04T15:02:36+00:00\",\"dateModified\":\"2023-03-07T18:23:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/#primaryimage\",\"url\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2023\/03\/803461288.jpg\",\"contentUrl\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2023\/03\/803461288.jpg\",\"width\":295,\"height\":166},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bannedvideos.net\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candida-Infektion und ein Ausweg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#website\",\"url\":\"https:\/\/bannedvideos.net\/en\/\",\"name\":\"Banned videos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/bannedvideos.net\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bannedvideos.net\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#organization\",\"name\":\"Banned videos\",\"url\":\"https:\/\/bannedvideos.net\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2022\/07\/logo.png\",\"contentUrl\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2022\/07\/logo.png\",\"width\":1496,\"height\":1441,\"caption\":\"Banned videos\"},\"image\":{\"@id\":\"https:\/\/bannedvideos.net\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/6901bae47f89066856a9d2c7faa5ebd2\",\"name\":\"bannedvideos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1f862b55a0861f605d25254d402b1f68536d9e9d320d9e14040debcefacf6342?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1f862b55a0861f605d25254d402b1f68536d9e9d320d9e14040debcefacf6342?s=96&d=mm&r=g\",\"caption\":\"bannedvideos\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Candida-Infektion und ein Ausweg - Banned videos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/","og_locale":"de_DE","og_type":"article","og_title":"Candida-Infektion und ein Ausweg - Banned videos","og_description":"Neben einer Candida-Infektion litt Hajnalka seit ihrem 12. Lebensjahr an Skoliose. Die beiden unterschiedlichen Probleme hatten sich seit Jahren gegenseitig beeinflusst. Hajnalka erz\u00e4hlt ihre Geschichte dar\u00fcber, wie sie es geschafft hat, sich nach vielen Jahren zu erholen.","og_url":"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/","og_site_name":"Banned videos","article_published_time":"2022-07-04T15:02:36+00:00","article_modified_time":"2023-03-07T18:23:46+00:00","og_image":[{"width":295,"height":166,"url":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2023\/03\/803461288.jpg","type":"image\/jpeg"}],"author":"bannedvideos","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"bannedvideos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ScholarlyArticle","@id":"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/#article","isPartOf":{"@id":"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/"},"author":{"name":"bannedvideos","@id":"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/6901bae47f89066856a9d2c7faa5ebd2"},"headline":"Candida-Infektion und ein Ausweg","datePublished":"2022-07-04T15:02:36+00:00","dateModified":"2023-03-07T18:23:46+00:00","mainEntityOfPage":{"@id":"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/"},"wordCount":42,"publisher":{"@id":"https:\/\/bannedvideos.net\/en\/#organization"},"image":{"@id":"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/#primaryimage"},"thumbnailUrl":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2023\/03\/803461288.jpg","articleSection":["Darmprobleme","Wirbels\u00e4ulenprobleme"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/","url":"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/","name":"Candida-Infektion und ein Ausweg - Banned videos","isPartOf":{"@id":"https:\/\/bannedvideos.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/#primaryimage"},"image":{"@id":"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/#primaryimage"},"thumbnailUrl":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2023\/03\/803461288.jpg","datePublished":"2022-07-04T15:02:36+00:00","dateModified":"2023-03-07T18:23:46+00:00","breadcrumb":{"@id":"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/#primaryimage","url":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2023\/03\/803461288.jpg","contentUrl":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2023\/03\/803461288.jpg","width":295,"height":166},{"@type":"BreadcrumbList","@id":"https:\/\/bannedvideos.net\/de\/candida-infektion-und-ein-ausweg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bannedvideos.net\/de\/"},{"@type":"ListItem","position":2,"name":"Candida-Infektion und ein Ausweg"}]},{"@type":"WebSite","@id":"https:\/\/bannedvideos.net\/en\/#website","url":"https:\/\/bannedvideos.net\/en\/","name":"Banned videos","description":"","publisher":{"@id":"https:\/\/bannedvideos.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bannedvideos.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/bannedvideos.net\/en\/#organization","name":"Banned videos","url":"https:\/\/bannedvideos.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bannedvideos.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2022\/07\/logo.png","contentUrl":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2022\/07\/logo.png","width":1496,"height":1441,"caption":"Banned videos"},"image":{"@id":"https:\/\/bannedvideos.net\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/6901bae47f89066856a9d2c7faa5ebd2","name":"bannedvideos","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1f862b55a0861f605d25254d402b1f68536d9e9d320d9e14040debcefacf6342?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f862b55a0861f605d25254d402b1f68536d9e9d320d9e14040debcefacf6342?s=96&d=mm&r=g","caption":"bannedvideos"}}]}},"_links":{"self":[{"href":"https:\/\/bannedvideos.net\/de\/wp-json\/wp\/v2\/posts\/70240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bannedvideos.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bannedvideos.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bannedvideos.net\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bannedvideos.net\/de\/wp-json\/wp\/v2\/comments?post=70240"}],"version-history":[{"count":0,"href":"https:\/\/bannedvideos.net\/de\/wp-json\/wp\/v2\/posts\/70240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bannedvideos.net\/de\/wp-json\/wp\/v2\/media\/70241"}],"wp:attachment":[{"href":"https:\/\/bannedvideos.net\/de\/wp-json\/wp\/v2\/media?parent=70240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bannedvideos.net\/de\/wp-json\/wp\/v2\/categories?post=70240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bannedvideos.net\/de\/wp-json\/wp\/v2\/tags?post=70240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}