{"id":113592,"date":"2024-05-12T12:20:20","date_gmt":"2024-05-12T10:20:20","guid":{"rendered":"https:\/\/bannedvideos.net\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/"},"modified":"2024-06-15T00:00:00","modified_gmt":"2024-06-14T22:00:00","slug":"krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo","status":"publish","type":"post","link":"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/","title":{"rendered":"Krisztina padec\u00eda una tos asm\u00e1tica que ya casi ha desaparecido por completo"},"content":{"rendered":"<p>Hace un a\u00f1o y medio, Krisztina sufri\u00f3 una tos asm\u00e1tica debido a una infecci\u00f3n anterior. Por eso, no s\u00f3lo el deporte, sino tambi\u00e9n las actividades cotidianas se le hicieron m\u00e1s dif\u00edciles y tuvo que usar broncodilatadores regularmente.<\/p>\n<p>Adem\u00e1s, not\u00f3 que el problema de reflujo de su hijo, que padec\u00eda desde hac\u00eda mucho tiempo, empezaba a mejorar. Otra ventaja es que D\u00e1vid puede prestar mejor atenci\u00f3n en la escuela y su sue\u00f1o tambi\u00e9n se ha vuelto m\u00e1s reparador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace un a\u00f1o y medio, Krisztina sufri\u00f3 una tos asm\u00e1tica debido a una infecci\u00f3n anterior. Por eso, no s\u00f3lo el deporte, sino tambi\u00e9n las actividades cotidianas se le hicieron m\u00e1s dif\u00edciles y tuvo que usar broncodilatadores regularmente. Adem\u00e1s, not\u00f3 que el problema de reflujo de su hijo, que padec\u00eda desde hac\u00eda mucho tiempo, empezaba a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":113593,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[630,330],"tags":[],"class_list":{"0":"post-113592","1":"post","2":"type-post","3":"status-publish","4":"format-video","5":"has-post-thumbnail","7":"category-asma","8":"category-problemas-intestinales","9":"post_format-post-format-video"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Krisztina padec\u00eda una tos asm\u00e1tica que ya casi ha desaparecido por completo - Banned videos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Krisztina padec\u00eda una tos asm\u00e1tica que ya casi ha desaparecido por completo - Banned videos\" \/>\n<meta property=\"og:description\" content=\"Hace un a\u00f1o y medio, Krisztina sufri\u00f3 una tos asm\u00e1tica debido a una infecci\u00f3n anterior. Por eso, no s\u00f3lo el deporte, sino tambi\u00e9n las actividades cotidianas se le hicieron m\u00e1s dif\u00edciles y tuvo que usar broncodilatadores regularmente. Adem\u00e1s, not\u00f3 que el problema de reflujo de su hijo, que padec\u00eda desde hac\u00eda mucho tiempo, empezaba a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/\" \/>\n<meta property=\"og:site_name\" content=\"Banned videos\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-12T10:20:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-14T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/06\/956461898.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"295\" \/>\n\t<meta property=\"og:image:height\" content=\"166\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bannedvideos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"bannedvideos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"ScholarlyArticle\",\"@id\":\"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/\"},\"author\":{\"name\":\"bannedvideos\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/5e11e476417d892fdf821a0299f37a62\"},\"headline\":\"Krisztina padec\u00eda una tos asm\u00e1tica que ya casi ha desaparecido por completo\",\"datePublished\":\"2024-05-12T10:20:20+00:00\",\"dateModified\":\"2024-06-14T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/\"},\"wordCount\":106,\"publisher\":{\"@id\":\"https:\/\/bannedvideos.net\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/06\/956461898.jpg\",\"articleSection\":[\"Asma\",\"Problemas intestinales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/\",\"url\":\"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/\",\"name\":\"Krisztina padec\u00eda una tos asm\u00e1tica que ya casi ha desaparecido por completo - Banned videos\",\"isPartOf\":{\"@id\":\"https:\/\/bannedvideos.net\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/06\/956461898.jpg\",\"datePublished\":\"2024-05-12T10:20:20+00:00\",\"dateModified\":\"2024-06-14T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/#primaryimage\",\"url\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/06\/956461898.jpg\",\"contentUrl\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/06\/956461898.jpg\",\"width\":295,\"height\":166},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bannedvideos.net\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Krisztina padec\u00eda una tos asm\u00e1tica que ya casi ha desaparecido por completo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#website\",\"url\":\"https:\/\/bannedvideos.net\/en\/\",\"name\":\"Banned videos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/bannedvideos.net\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bannedvideos.net\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#organization\",\"name\":\"Banned videos\",\"url\":\"https:\/\/bannedvideos.net\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2022\/07\/logo.png\",\"contentUrl\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2022\/07\/logo.png\",\"width\":1496,\"height\":1441,\"caption\":\"Banned videos\"},\"image\":{\"@id\":\"https:\/\/bannedvideos.net\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/5e11e476417d892fdf821a0299f37a62\",\"name\":\"bannedvideos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b843d2076fa08453002de35683e5a2f818cd3e18d2d4a37f2404adb0f08098b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b843d2076fa08453002de35683e5a2f818cd3e18d2d4a37f2404adb0f08098b1?s=96&d=mm&r=g\",\"caption\":\"bannedvideos\"},\"sameAs\":[\"http:\/\/cpeptide.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Krisztina padec\u00eda una tos asm\u00e1tica que ya casi ha desaparecido por completo - Banned videos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/","og_locale":"es_ES","og_type":"article","og_title":"Krisztina padec\u00eda una tos asm\u00e1tica que ya casi ha desaparecido por completo - Banned videos","og_description":"Hace un a\u00f1o y medio, Krisztina sufri\u00f3 una tos asm\u00e1tica debido a una infecci\u00f3n anterior. Por eso, no s\u00f3lo el deporte, sino tambi\u00e9n las actividades cotidianas se le hicieron m\u00e1s dif\u00edciles y tuvo que usar broncodilatadores regularmente. Adem\u00e1s, not\u00f3 que el problema de reflujo de su hijo, que padec\u00eda desde hac\u00eda mucho tiempo, empezaba a [&hellip;]","og_url":"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/","og_site_name":"Banned videos","article_published_time":"2024-05-12T10:20:20+00:00","article_modified_time":"2024-06-14T22:00:00+00:00","og_image":[{"width":295,"height":166,"url":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/06\/956461898.jpg","type":"image\/jpeg"}],"author":"bannedvideos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"bannedvideos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ScholarlyArticle","@id":"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/#article","isPartOf":{"@id":"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/"},"author":{"name":"bannedvideos","@id":"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/5e11e476417d892fdf821a0299f37a62"},"headline":"Krisztina padec\u00eda una tos asm\u00e1tica que ya casi ha desaparecido por completo","datePublished":"2024-05-12T10:20:20+00:00","dateModified":"2024-06-14T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/"},"wordCount":106,"publisher":{"@id":"https:\/\/bannedvideos.net\/en\/#organization"},"image":{"@id":"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/#primaryimage"},"thumbnailUrl":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/06\/956461898.jpg","articleSection":["Asma","Problemas intestinales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/","url":"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/","name":"Krisztina padec\u00eda una tos asm\u00e1tica que ya casi ha desaparecido por completo - Banned videos","isPartOf":{"@id":"https:\/\/bannedvideos.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/#primaryimage"},"image":{"@id":"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/#primaryimage"},"thumbnailUrl":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/06\/956461898.jpg","datePublished":"2024-05-12T10:20:20+00:00","dateModified":"2024-06-14T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/#primaryimage","url":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/06\/956461898.jpg","contentUrl":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/06\/956461898.jpg","width":295,"height":166},{"@type":"BreadcrumbList","@id":"https:\/\/bannedvideos.net\/es\/krisztina-padecia-una-tos-asmatica-que-ya-casi-ha-desaparecido-por-completo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bannedvideos.net\/es\/"},{"@type":"ListItem","position":2,"name":"Krisztina padec\u00eda una tos asm\u00e1tica que ya casi ha desaparecido por completo"}]},{"@type":"WebSite","@id":"https:\/\/bannedvideos.net\/en\/#website","url":"https:\/\/bannedvideos.net\/en\/","name":"Banned videos","description":"","publisher":{"@id":"https:\/\/bannedvideos.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bannedvideos.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/bannedvideos.net\/en\/#organization","name":"Banned videos","url":"https:\/\/bannedvideos.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bannedvideos.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2022\/07\/logo.png","contentUrl":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2022\/07\/logo.png","width":1496,"height":1441,"caption":"Banned videos"},"image":{"@id":"https:\/\/bannedvideos.net\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/5e11e476417d892fdf821a0299f37a62","name":"bannedvideos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b843d2076fa08453002de35683e5a2f818cd3e18d2d4a37f2404adb0f08098b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b843d2076fa08453002de35683e5a2f818cd3e18d2d4a37f2404adb0f08098b1?s=96&d=mm&r=g","caption":"bannedvideos"},"sameAs":["http:\/\/cpeptide.com"]}]}},"_links":{"self":[{"href":"https:\/\/bannedvideos.net\/es\/wp-json\/wp\/v2\/posts\/113592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bannedvideos.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bannedvideos.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bannedvideos.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bannedvideos.net\/es\/wp-json\/wp\/v2\/comments?post=113592"}],"version-history":[{"count":0,"href":"https:\/\/bannedvideos.net\/es\/wp-json\/wp\/v2\/posts\/113592\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bannedvideos.net\/es\/wp-json\/wp\/v2\/media\/113593"}],"wp:attachment":[{"href":"https:\/\/bannedvideos.net\/es\/wp-json\/wp\/v2\/media?parent=113592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bannedvideos.net\/es\/wp-json\/wp\/v2\/categories?post=113592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bannedvideos.net\/es\/wp-json\/wp\/v2\/tags?post=113592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}