{"id":112088,"date":"2023-02-02T00:25:58","date_gmt":"2023-02-01T22:25:58","guid":{"rendered":"https:\/\/bannedvideos.net\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/"},"modified":"2024-05-12T17:53:18","modified_gmt":"2024-05-12T15:53:18","slug":"istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare","status":"publish","type":"post","link":"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/","title":{"rendered":"Istv\u00e1n a c\u0103zut bolnav la pat din cauza unei hipotonii musculare"},"content":{"rendered":"<p>Miastenia gravis a lui Istv\u00e1n l-a l\u0103sat imobilizat. A trebuit s\u0103 renun\u021be la hobby-ul s\u0103u preferat: \u00eengrijirea gr\u0103dinii dragi. Atunci a descoperit peptida-C, care l-a ajutat s\u0103 se pun\u0103 pe picioare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miastenia gravis a lui Istv\u00e1n l-a l\u0103sat imobilizat. A trebuit s\u0103 renun\u021be la hobby-ul s\u0103u preferat: \u00eengrijirea gr\u0103dinii dragi. Atunci a descoperit peptida-C, care l-a ajutat s\u0103 se pun\u0103 pe picioare.<\/p>\n","protected":false},"author":4,"featured_media":112089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[1217,1218],"tags":[],"class_list":{"0":"post-112088","1":"post","2":"type-post","3":"status-publish","4":"format-video","5":"has-post-thumbnail","7":"category-boala-autoimuna","8":"category-boli-cardiovasculare","9":"post_format-post-format-video"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Istv\u00e1n a c\u0103zut bolnav la pat din cauza unei hipotonii musculare - Banned videos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Istv\u00e1n a c\u0103zut bolnav la pat din cauza unei hipotonii musculare - Banned videos\" \/>\n<meta property=\"og:description\" content=\"Miastenia gravis a lui Istv\u00e1n l-a l\u0103sat imobilizat. A trebuit s\u0103 renun\u021be la hobby-ul s\u0103u preferat: \u00eengrijirea gr\u0103dinii dragi. Atunci a descoperit peptida-C, care l-a ajutat s\u0103 se pun\u0103 pe picioare.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/\" \/>\n<meta property=\"og:site_name\" content=\"Banned videos\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-01T22:25:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-12T15:53:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/05\/821337067.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"295\" \/>\n\t<meta property=\"og:image:height\" content=\"166\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bannedvideos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scris de\" \/>\n\t<meta name=\"twitter:data1\" content=\"bannedvideos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"ScholarlyArticle\",\"@id\":\"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/\"},\"author\":{\"name\":\"bannedvideos\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/6901bae47f89066856a9d2c7faa5ebd2\"},\"headline\":\"Istv\u00e1n a c\u0103zut bolnav la pat din cauza unei hipotonii musculare\",\"datePublished\":\"2023-02-01T22:25:58+00:00\",\"dateModified\":\"2024-05-12T15:53:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/\"},\"wordCount\":49,\"publisher\":{\"@id\":\"https:\/\/bannedvideos.net\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/05\/821337067.jpg\",\"articleSection\":[\"Boal\u0103 autoimun\u0103\",\"Boli cardiovasculare\"],\"inLanguage\":\"ro-RO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/\",\"url\":\"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/\",\"name\":\"Istv\u00e1n a c\u0103zut bolnav la pat din cauza unei hipotonii musculare - Banned videos\",\"isPartOf\":{\"@id\":\"https:\/\/bannedvideos.net\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/05\/821337067.jpg\",\"datePublished\":\"2023-02-01T22:25:58+00:00\",\"dateModified\":\"2024-05-12T15:53:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/#primaryimage\",\"url\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/05\/821337067.jpg\",\"contentUrl\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/05\/821337067.jpg\",\"width\":295,\"height\":166},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bannedvideos.net\/ro\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Istv\u00e1n a c\u0103zut bolnav la pat din cauza unei hipotonii musculare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#website\",\"url\":\"https:\/\/bannedvideos.net\/en\/\",\"name\":\"Banned videos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/bannedvideos.net\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bannedvideos.net\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#organization\",\"name\":\"Banned videos\",\"url\":\"https:\/\/bannedvideos.net\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2022\/07\/logo.png\",\"contentUrl\":\"https:\/\/bannedvideos.net\/wp-content\/uploads\/2022\/07\/logo.png\",\"width\":1496,\"height\":1441,\"caption\":\"Banned videos\"},\"image\":{\"@id\":\"https:\/\/bannedvideos.net\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/6901bae47f89066856a9d2c7faa5ebd2\",\"name\":\"bannedvideos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1f862b55a0861f605d25254d402b1f68536d9e9d320d9e14040debcefacf6342?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1f862b55a0861f605d25254d402b1f68536d9e9d320d9e14040debcefacf6342?s=96&d=mm&r=g\",\"caption\":\"bannedvideos\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Istv\u00e1n a c\u0103zut bolnav la pat din cauza unei hipotonii musculare - Banned videos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/","og_locale":"ro_RO","og_type":"article","og_title":"Istv\u00e1n a c\u0103zut bolnav la pat din cauza unei hipotonii musculare - Banned videos","og_description":"Miastenia gravis a lui Istv\u00e1n l-a l\u0103sat imobilizat. A trebuit s\u0103 renun\u021be la hobby-ul s\u0103u preferat: \u00eengrijirea gr\u0103dinii dragi. Atunci a descoperit peptida-C, care l-a ajutat s\u0103 se pun\u0103 pe picioare.","og_url":"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/","og_site_name":"Banned videos","article_published_time":"2023-02-01T22:25:58+00:00","article_modified_time":"2024-05-12T15:53:18+00:00","og_image":[{"width":295,"height":166,"url":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/05\/821337067.jpg","type":"image\/jpeg"}],"author":"bannedvideos","twitter_card":"summary_large_image","twitter_misc":{"Scris de":"bannedvideos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ScholarlyArticle","@id":"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/#article","isPartOf":{"@id":"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/"},"author":{"name":"bannedvideos","@id":"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/6901bae47f89066856a9d2c7faa5ebd2"},"headline":"Istv\u00e1n a c\u0103zut bolnav la pat din cauza unei hipotonii musculare","datePublished":"2023-02-01T22:25:58+00:00","dateModified":"2024-05-12T15:53:18+00:00","mainEntityOfPage":{"@id":"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/"},"wordCount":49,"publisher":{"@id":"https:\/\/bannedvideos.net\/en\/#organization"},"image":{"@id":"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/#primaryimage"},"thumbnailUrl":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/05\/821337067.jpg","articleSection":["Boal\u0103 autoimun\u0103","Boli cardiovasculare"],"inLanguage":"ro-RO"},{"@type":"WebPage","@id":"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/","url":"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/","name":"Istv\u00e1n a c\u0103zut bolnav la pat din cauza unei hipotonii musculare - Banned videos","isPartOf":{"@id":"https:\/\/bannedvideos.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/#primaryimage"},"image":{"@id":"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/#primaryimage"},"thumbnailUrl":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/05\/821337067.jpg","datePublished":"2023-02-01T22:25:58+00:00","dateModified":"2024-05-12T15:53:18+00:00","breadcrumb":{"@id":"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/#primaryimage","url":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/05\/821337067.jpg","contentUrl":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2024\/05\/821337067.jpg","width":295,"height":166},{"@type":"BreadcrumbList","@id":"https:\/\/bannedvideos.net\/ro\/istvan-a-cazut-bolnav-la-pat-din-cauza-unei-hipotonii-musculare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bannedvideos.net\/ro\/home\/"},{"@type":"ListItem","position":2,"name":"Istv\u00e1n a c\u0103zut bolnav la pat din cauza unei hipotonii musculare"}]},{"@type":"WebSite","@id":"https:\/\/bannedvideos.net\/en\/#website","url":"https:\/\/bannedvideos.net\/en\/","name":"Banned videos","description":"","publisher":{"@id":"https:\/\/bannedvideos.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bannedvideos.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/bannedvideos.net\/en\/#organization","name":"Banned videos","url":"https:\/\/bannedvideos.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/bannedvideos.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2022\/07\/logo.png","contentUrl":"https:\/\/bannedvideos.net\/wp-content\/uploads\/2022\/07\/logo.png","width":1496,"height":1441,"caption":"Banned videos"},"image":{"@id":"https:\/\/bannedvideos.net\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/6901bae47f89066856a9d2c7faa5ebd2","name":"bannedvideos","image":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/bannedvideos.net\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1f862b55a0861f605d25254d402b1f68536d9e9d320d9e14040debcefacf6342?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f862b55a0861f605d25254d402b1f68536d9e9d320d9e14040debcefacf6342?s=96&d=mm&r=g","caption":"bannedvideos"}}]}},"_links":{"self":[{"href":"https:\/\/bannedvideos.net\/ro\/wp-json\/wp\/v2\/posts\/112088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bannedvideos.net\/ro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bannedvideos.net\/ro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bannedvideos.net\/ro\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bannedvideos.net\/ro\/wp-json\/wp\/v2\/comments?post=112088"}],"version-history":[{"count":0,"href":"https:\/\/bannedvideos.net\/ro\/wp-json\/wp\/v2\/posts\/112088\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bannedvideos.net\/ro\/wp-json\/wp\/v2\/media\/112089"}],"wp:attachment":[{"href":"https:\/\/bannedvideos.net\/ro\/wp-json\/wp\/v2\/media?parent=112088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bannedvideos.net\/ro\/wp-json\/wp\/v2\/categories?post=112088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bannedvideos.net\/ro\/wp-json\/wp\/v2\/tags?post=112088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}